{"id":39033,"date":"2012-11-30T15:46:16","date_gmt":"2012-11-30T18:46:16","guid":{"rendered":"http:\/\/www.encontrasantana.com.br\/blog\/?p=39033"},"modified":"2019-04-15T09:58:24","modified_gmt":"2019-04-15T12:58:24","slug":"bilhete-unico-ganha-recarga-movel-no-metro-santana","status":"publish","type":"post","link":"https:\/\/www.encontrasantana.com.br\/sobre\/bilhete-unico-ganha-recarga-movel-no-metro-santana\/","title":{"rendered":"Bilhete \u00danico ganha recarga m\u00f3vel no Metr\u00f4 Santana"},"content":{"rendered":"<div class=\"1acf8468e559fd3cbeec5aee3a269a52\" data-index=\"1\" style=\"float: none; margin:0px;\">\n<!-- Anuncio display - global -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"8789329856\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>Depois de os usu\u00e1rios do Metr\u00f4 enfrentarem problemas para recarregar o Bilhete \u00danico, a SPTrans come\u00e7ou nesta quinta-feira uma \u201ca\u00e7\u00e3o emergencial e tempor\u00e1ria para minimizar as dificuldades no sistema\u201d. Um carregamento m\u00f3vel est\u00e1 dispon\u00edvel nas sa\u00eddas da\u00a0<a title=\"Esta\u00e7\u00e3o Santana\" href=\"http:\/\/www.encontrasantana.com.br\/santana\/metro-santana.shtml\" target=\"_blank\">Esta\u00e7\u00e3o Santana<\/a>,\u00a0Esta\u00e7\u00e3o Tucuruvi,\u00a0Esta\u00e7\u00e3o Vila Mariana, Esta\u00e7\u00e3o Arthur Alvim e\u00a0Esta\u00e7\u00e3o Santa Cruz\u00a0para fazer a recarga dos bilhetes. Os usu\u00e1rios poder\u00e3o inserir cr\u00e9ditos com dinheiro ou cart\u00e3o de d\u00e9bito. Funcion\u00e1rios est\u00e3o identificados com coletes.<\/p>\n<p>A partir da pr\u00f3xima segunda-feira, o atendimento m\u00f3vel deve ser estendido as demais esta\u00e7\u00f5es onde a empresa\u00a0Servi\u00e7o\u00a0Digitais deixou de atender, totalizando 17 pontos volantes.<\/p>\n<p>Segundo a SPTrans, a Servi\u00e7os Digitais atrasou repasses para a\u00a0Prefeitura de S\u00e3o Paulo, recebeu cerca de 30 multas e foi impedida de realizar recargas. Na ter\u00e7a-feira, o \u00f3rg\u00e3o informou que fazia 15 dias que a empresa havia deixado de repassar para a administra\u00e7\u00e3o municipal os valores arrecadados com a venda dos cr\u00e9ditos.<\/p>\n<p>De acordo com a SPTrans, nos arredores das esta\u00e7\u00f5es do Metr\u00f4 existem bancas de jornais, bares, restaurantes e casas lot\u00e9ricas nos quais a recarga pode ser feita. O \u00f3rg\u00e3o municipal estima em mais de dez mil os postos credenciados em toda a cidade, al\u00e9m dos 28 terminais de \u00f4nibus onde as recargas podem ser feitas 24 horas por dia.<\/p>\n<p><em>Fonte: Rede Bom Dia<\/em><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Depois de os usu\u00e1rios do Metr\u00f4 enfrentarem problemas para recarregar o Bilhete \u00danico, a SPTrans come\u00e7ou nesta quinta-feira uma \u201ca\u00e7\u00e3o emergencial e tempor\u00e1ria para minimizar as dificuldades no sistema\u201d. Um carregamento m\u00f3vel est\u00e1 dispon\u00edvel nas sa\u00eddas da\u00a0Esta\u00e7\u00e3o Santana,\u00a0Esta\u00e7\u00e3o Tucuruvi,\u00a0Esta\u00e7\u00e3o Vila Mariana, Esta\u00e7\u00e3o Arthur Alvim e\u00a0Esta\u00e7\u00e3o Santa Cruz\u00a0para fazer a recarga dos bilhetes. Os usu\u00e1rios poder\u00e3o inserir cr\u00e9ditos com dinheiro ou cart\u00e3o de d\u00e9bito. Funcion\u00e1rios est\u00e3o identificados com coletes. A partir da pr\u00f3xima segunda-feira, o atendimento m\u00f3vel deve ser estendido as demais esta\u00e7\u00f5es onde a empresa\u00a0Servi\u00e7o\u00a0Digitais deixou de atender, totalizando 17 pontos volantes. Segundo a SPTrans, a Servi\u00e7os Digitais atrasou repasses <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[10],"class_list":["post-39033","post","type-post","status-publish","format-standard","hentry","category-noticias-em-santana","tag-santana"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Depois de os usu\u00e1rios do Metr\u00f4 enfrentarem problemas para recarregar o Bilhete \u00danico, a SPTrans come\u00e7ou nesta quinta-feira uma \u201ca\u00e7\u00e3o emergencial e tempor\u00e1ria para minimizar as dificuldades no sistema\u201d. Um carregamento m\u00f3vel est\u00e1 dispon\u00edvel nas sa\u00eddas da Esta\u00e7\u00e3o Santana, Esta\u00e7\u00e3o Tucuruvi, Esta\u00e7\u00e3o Vila Mariana, Esta\u00e7\u00e3o Arthur Alvim e Esta\u00e7\u00e3o Santa Cruz para fazer a recarga dos bilhetes. Os usu\u00e1rios poder\u00e3o\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Encontra Santana\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.encontrasantana.com.br\/sobre\/bilhete-unico-ganha-recarga-movel-no-metro-santana\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Encontra Santana | Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas no bairro de Santana e regi\u00e3o.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Bilhete \u00danico ganha recarga m\u00f3vel no Metr\u00f4 Santana \u00bb Encontra Santana\" \/>\n\t\t<meta property=\"og:description\" content=\"Depois de os usu\u00e1rios do Metr\u00f4 enfrentarem problemas para recarregar o Bilhete \u00danico, a SPTrans come\u00e7ou nesta quinta-feira uma \u201ca\u00e7\u00e3o emergencial e tempor\u00e1ria para minimizar as dificuldades no sistema\u201d. Um carregamento m\u00f3vel est\u00e1 dispon\u00edvel nas sa\u00eddas da Esta\u00e7\u00e3o Santana, Esta\u00e7\u00e3o Tucuruvi, Esta\u00e7\u00e3o Vila Mariana, Esta\u00e7\u00e3o Arthur Alvim e Esta\u00e7\u00e3o Santa Cruz para fazer a recarga dos bilhetes. Os usu\u00e1rios poder\u00e3o\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.encontrasantana.com.br\/sobre\/bilhete-unico-ganha-recarga-movel-no-metro-santana\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2012-11-30T18:46:16+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-04-15T12:58:24+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Bilhete \u00danico ganha recarga m\u00f3vel no Metr\u00f4 Santana \u00bb Encontra Santana\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Depois de os usu\u00e1rios do Metr\u00f4 enfrentarem problemas para recarregar o Bilhete \u00danico, a SPTrans come\u00e7ou nesta quinta-feira uma \u201ca\u00e7\u00e3o emergencial e tempor\u00e1ria para minimizar as dificuldades no sistema\u201d. Um carregamento m\u00f3vel est\u00e1 dispon\u00edvel nas sa\u00eddas da Esta\u00e7\u00e3o Santana, Esta\u00e7\u00e3o Tucuruvi, Esta\u00e7\u00e3o Vila Mariana, Esta\u00e7\u00e3o Arthur Alvim e Esta\u00e7\u00e3o Santa Cruz para fazer a recarga dos bilhetes. Os usu\u00e1rios poder\u00e3o\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.encontrasantana.com.br\\\/sobre\\\/bilhete-unico-ganha-recarga-movel-no-metro-santana\\\/#article\",\"name\":\"Bilhete \\u00danico ganha recarga m\\u00f3vel no Metr\\u00f4 Santana \\u00bb Encontra Santana\",\"headline\":\"Bilhete \\u00danico ganha recarga m\\u00f3vel no Metr\\u00f4 Santana\",\"author\":{\"@id\":\"https:\\\/\\\/www.encontrasantana.com.br\\\/sobre\\\/author\\\/esantana\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.encontrasantana.com.br\\\/sobre\\\/#organization\"},\"datePublished\":\"2012-11-30T15:46:16-03:00\",\"dateModified\":\"2019-04-15T09:58:24-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.encontrasantana.com.br\\\/sobre\\\/bilhete-unico-ganha-recarga-movel-no-metro-santana\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontrasantana.com.br\\\/sobre\\\/bilhete-unico-ganha-recarga-movel-no-metro-santana\\\/#webpage\"},\"articleSection\":\"Not\\u00edcias Santana, Santana\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.encontrasantana.com.br\\\/sobre\\\/bilhete-unico-ganha-recarga-movel-no-metro-santana\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontrasantana.com.br\\\/sobre#listItem\",\"position\":1,\"name\":\"In\\u00edcio\",\"item\":\"https:\\\/\\\/www.encontrasantana.com.br\\\/sobre\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontrasantana.com.br\\\/sobre\\\/noticias-em-santana\\\/#listItem\",\"name\":\"Not\\u00edcias Santana\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontrasantana.com.br\\\/sobre\\\/noticias-em-santana\\\/#listItem\",\"position\":2,\"name\":\"Not\\u00edcias Santana\",\"item\":\"https:\\\/\\\/www.encontrasantana.com.br\\\/sobre\\\/noticias-em-santana\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontrasantana.com.br\\\/sobre\\\/bilhete-unico-ganha-recarga-movel-no-metro-santana\\\/#listItem\",\"name\":\"Bilhete \\u00danico ganha recarga m\\u00f3vel no Metr\\u00f4 Santana\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontrasantana.com.br\\\/sobre#listItem\",\"name\":\"In\\u00edcio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontrasantana.com.br\\\/sobre\\\/bilhete-unico-ganha-recarga-movel-no-metro-santana\\\/#listItem\",\"position\":3,\"name\":\"Bilhete \\u00danico ganha recarga m\\u00f3vel no Metr\\u00f4 Santana\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontrasantana.com.br\\\/sobre\\\/noticias-em-santana\\\/#listItem\",\"name\":\"Not\\u00edcias Santana\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.encontrasantana.com.br\\\/sobre\\\/#organization\",\"name\":\"Encontra Santana\",\"description\":\"Not\\u00edcias, eventos, informa\\u00e7\\u00f5es e dicas no bairro de Santana e regi\\u00e3o.\",\"url\":\"https:\\\/\\\/www.encontrasantana.com.br\\\/sobre\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.encontrasantana.com.br\\\/sobre\\\/author\\\/esantana\\\/#author\",\"url\":\"https:\\\/\\\/www.encontrasantana.com.br\\\/sobre\\\/author\\\/esantana\\\/\",\"name\":\"Encontra Santana\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.encontrasantana.com.br\\\/sobre\\\/bilhete-unico-ganha-recarga-movel-no-metro-santana\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0fbed662e37531ae23e68f85f9517b2454e50c1dfebf80eb9b721449ac95e0b9?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Encontra Santana\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.encontrasantana.com.br\\\/sobre\\\/bilhete-unico-ganha-recarga-movel-no-metro-santana\\\/#webpage\",\"url\":\"https:\\\/\\\/www.encontrasantana.com.br\\\/sobre\\\/bilhete-unico-ganha-recarga-movel-no-metro-santana\\\/\",\"name\":\"Bilhete \\u00danico ganha recarga m\\u00f3vel no Metr\\u00f4 Santana \\u00bb Encontra Santana\",\"description\":\"Depois de os usu\\u00e1rios do Metr\\u00f4 enfrentarem problemas para recarregar o Bilhete \\u00danico, a SPTrans come\\u00e7ou nesta quinta-feira uma \\u201ca\\u00e7\\u00e3o emergencial e tempor\\u00e1ria para minimizar as dificuldades no sistema\\u201d. Um carregamento m\\u00f3vel est\\u00e1 dispon\\u00edvel nas sa\\u00eddas da Esta\\u00e7\\u00e3o Santana, Esta\\u00e7\\u00e3o Tucuruvi, Esta\\u00e7\\u00e3o Vila Mariana, Esta\\u00e7\\u00e3o Arthur Alvim e Esta\\u00e7\\u00e3o Santa Cruz para fazer a recarga dos bilhetes. Os usu\\u00e1rios poder\\u00e3o\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontrasantana.com.br\\\/sobre\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.encontrasantana.com.br\\\/sobre\\\/bilhete-unico-ganha-recarga-movel-no-metro-santana\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.encontrasantana.com.br\\\/sobre\\\/author\\\/esantana\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.encontrasantana.com.br\\\/sobre\\\/author\\\/esantana\\\/#author\"},\"datePublished\":\"2012-11-30T15:46:16-03:00\",\"dateModified\":\"2019-04-15T09:58:24-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.encontrasantana.com.br\\\/sobre\\\/#website\",\"url\":\"https:\\\/\\\/www.encontrasantana.com.br\\\/sobre\\\/\",\"name\":\"Encontra Santana\",\"description\":\"Not\\u00edcias, eventos, informa\\u00e7\\u00f5es e dicas no bairro de Santana e regi\\u00e3o.\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.encontrasantana.com.br\\\/sobre\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Bilhete \u00danico ganha recarga m\u00f3vel no Metr\u00f4 Santana \u00bb Encontra Santana","description":"Depois de os usu\u00e1rios do Metr\u00f4 enfrentarem problemas para recarregar o Bilhete \u00danico, a SPTrans come\u00e7ou nesta quinta-feira uma \u201ca\u00e7\u00e3o emergencial e tempor\u00e1ria para minimizar as dificuldades no sistema\u201d. Um carregamento m\u00f3vel est\u00e1 dispon\u00edvel nas sa\u00eddas da Esta\u00e7\u00e3o Santana, Esta\u00e7\u00e3o Tucuruvi, Esta\u00e7\u00e3o Vila Mariana, Esta\u00e7\u00e3o Arthur Alvim e Esta\u00e7\u00e3o Santa Cruz para fazer a recarga dos bilhetes. Os usu\u00e1rios poder\u00e3o","canonical_url":"https:\/\/www.encontrasantana.com.br\/sobre\/bilhete-unico-ganha-recarga-movel-no-metro-santana\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.encontrasantana.com.br\/sobre\/bilhete-unico-ganha-recarga-movel-no-metro-santana\/#article","name":"Bilhete \u00danico ganha recarga m\u00f3vel no Metr\u00f4 Santana \u00bb Encontra Santana","headline":"Bilhete \u00danico ganha recarga m\u00f3vel no Metr\u00f4 Santana","author":{"@id":"https:\/\/www.encontrasantana.com.br\/sobre\/author\/esantana\/#author"},"publisher":{"@id":"https:\/\/www.encontrasantana.com.br\/sobre\/#organization"},"datePublished":"2012-11-30T15:46:16-03:00","dateModified":"2019-04-15T09:58:24-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/www.encontrasantana.com.br\/sobre\/bilhete-unico-ganha-recarga-movel-no-metro-santana\/#webpage"},"isPartOf":{"@id":"https:\/\/www.encontrasantana.com.br\/sobre\/bilhete-unico-ganha-recarga-movel-no-metro-santana\/#webpage"},"articleSection":"Not\u00edcias Santana, Santana"},{"@type":"BreadcrumbList","@id":"https:\/\/www.encontrasantana.com.br\/sobre\/bilhete-unico-ganha-recarga-movel-no-metro-santana\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.encontrasantana.com.br\/sobre#listItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.encontrasantana.com.br\/sobre","nextItem":{"@type":"ListItem","@id":"https:\/\/www.encontrasantana.com.br\/sobre\/noticias-em-santana\/#listItem","name":"Not\u00edcias Santana"}},{"@type":"ListItem","@id":"https:\/\/www.encontrasantana.com.br\/sobre\/noticias-em-santana\/#listItem","position":2,"name":"Not\u00edcias Santana","item":"https:\/\/www.encontrasantana.com.br\/sobre\/noticias-em-santana\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.encontrasantana.com.br\/sobre\/bilhete-unico-ganha-recarga-movel-no-metro-santana\/#listItem","name":"Bilhete \u00danico ganha recarga m\u00f3vel no Metr\u00f4 Santana"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.encontrasantana.com.br\/sobre#listItem","name":"In\u00edcio"}},{"@type":"ListItem","@id":"https:\/\/www.encontrasantana.com.br\/sobre\/bilhete-unico-ganha-recarga-movel-no-metro-santana\/#listItem","position":3,"name":"Bilhete \u00danico ganha recarga m\u00f3vel no Metr\u00f4 Santana","previousItem":{"@type":"ListItem","@id":"https:\/\/www.encontrasantana.com.br\/sobre\/noticias-em-santana\/#listItem","name":"Not\u00edcias Santana"}}]},{"@type":"Organization","@id":"https:\/\/www.encontrasantana.com.br\/sobre\/#organization","name":"Encontra Santana","description":"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas no bairro de Santana e regi\u00e3o.","url":"https:\/\/www.encontrasantana.com.br\/sobre\/"},{"@type":"Person","@id":"https:\/\/www.encontrasantana.com.br\/sobre\/author\/esantana\/#author","url":"https:\/\/www.encontrasantana.com.br\/sobre\/author\/esantana\/","name":"Encontra Santana","image":{"@type":"ImageObject","@id":"https:\/\/www.encontrasantana.com.br\/sobre\/bilhete-unico-ganha-recarga-movel-no-metro-santana\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/0fbed662e37531ae23e68f85f9517b2454e50c1dfebf80eb9b721449ac95e0b9?s=96&d=mm&r=g","width":96,"height":96,"caption":"Encontra Santana"}},{"@type":"WebPage","@id":"https:\/\/www.encontrasantana.com.br\/sobre\/bilhete-unico-ganha-recarga-movel-no-metro-santana\/#webpage","url":"https:\/\/www.encontrasantana.com.br\/sobre\/bilhete-unico-ganha-recarga-movel-no-metro-santana\/","name":"Bilhete \u00danico ganha recarga m\u00f3vel no Metr\u00f4 Santana \u00bb Encontra Santana","description":"Depois de os usu\u00e1rios do Metr\u00f4 enfrentarem problemas para recarregar o Bilhete \u00danico, a SPTrans come\u00e7ou nesta quinta-feira uma \u201ca\u00e7\u00e3o emergencial e tempor\u00e1ria para minimizar as dificuldades no sistema\u201d. Um carregamento m\u00f3vel est\u00e1 dispon\u00edvel nas sa\u00eddas da Esta\u00e7\u00e3o Santana, Esta\u00e7\u00e3o Tucuruvi, Esta\u00e7\u00e3o Vila Mariana, Esta\u00e7\u00e3o Arthur Alvim e Esta\u00e7\u00e3o Santa Cruz para fazer a recarga dos bilhetes. Os usu\u00e1rios poder\u00e3o","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/www.encontrasantana.com.br\/sobre\/#website"},"breadcrumb":{"@id":"https:\/\/www.encontrasantana.com.br\/sobre\/bilhete-unico-ganha-recarga-movel-no-metro-santana\/#breadcrumblist"},"author":{"@id":"https:\/\/www.encontrasantana.com.br\/sobre\/author\/esantana\/#author"},"creator":{"@id":"https:\/\/www.encontrasantana.com.br\/sobre\/author\/esantana\/#author"},"datePublished":"2012-11-30T15:46:16-03:00","dateModified":"2019-04-15T09:58:24-03:00"},{"@type":"WebSite","@id":"https:\/\/www.encontrasantana.com.br\/sobre\/#website","url":"https:\/\/www.encontrasantana.com.br\/sobre\/","name":"Encontra Santana","description":"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas no bairro de Santana e regi\u00e3o.","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/www.encontrasantana.com.br\/sobre\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Encontra Santana | Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas no bairro de Santana e regi\u00e3o.","og:type":"article","og:title":"Bilhete \u00danico ganha recarga m\u00f3vel no Metr\u00f4 Santana \u00bb Encontra Santana","og:description":"Depois de os usu\u00e1rios do Metr\u00f4 enfrentarem problemas para recarregar o Bilhete \u00danico, a SPTrans come\u00e7ou nesta quinta-feira uma \u201ca\u00e7\u00e3o emergencial e tempor\u00e1ria para minimizar as dificuldades no sistema\u201d. Um carregamento m\u00f3vel est\u00e1 dispon\u00edvel nas sa\u00eddas da Esta\u00e7\u00e3o Santana, Esta\u00e7\u00e3o Tucuruvi, Esta\u00e7\u00e3o Vila Mariana, Esta\u00e7\u00e3o Arthur Alvim e Esta\u00e7\u00e3o Santa Cruz para fazer a recarga dos bilhetes. Os usu\u00e1rios poder\u00e3o","og:url":"https:\/\/www.encontrasantana.com.br\/sobre\/bilhete-unico-ganha-recarga-movel-no-metro-santana\/","article:published_time":"2012-11-30T18:46:16+00:00","article:modified_time":"2019-04-15T12:58:24+00:00","twitter:card":"summary","twitter:title":"Bilhete \u00danico ganha recarga m\u00f3vel no Metr\u00f4 Santana \u00bb Encontra Santana","twitter:description":"Depois de os usu\u00e1rios do Metr\u00f4 enfrentarem problemas para recarregar o Bilhete \u00danico, a SPTrans come\u00e7ou nesta quinta-feira uma \u201ca\u00e7\u00e3o emergencial e tempor\u00e1ria para minimizar as dificuldades no sistema\u201d. Um carregamento m\u00f3vel est\u00e1 dispon\u00edvel nas sa\u00eddas da Esta\u00e7\u00e3o Santana, Esta\u00e7\u00e3o Tucuruvi, Esta\u00e7\u00e3o Vila Mariana, Esta\u00e7\u00e3o Arthur Alvim e Esta\u00e7\u00e3o Santa Cruz para fazer a recarga dos bilhetes. Os usu\u00e1rios poder\u00e3o"},"aioseo_meta_data":{"post_id":"39033","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2021-04-20 18:36:01","updated":"2026-08-06 10:24:57","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.encontrasantana.com.br\/sobre\" title=\"In\u00edcio\">In\u00edcio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.encontrasantana.com.br\/sobre\/noticias-em-santana\/\" title=\"Not\u00edcias Santana\">Not\u00edcias Santana<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tBilhete \u00danico ganha recarga m\u00f3vel no Metr\u00f4 Santana\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"In\u00edcio","link":"https:\/\/www.encontrasantana.com.br\/sobre"},{"label":"Not\u00edcias Santana","link":"https:\/\/www.encontrasantana.com.br\/sobre\/noticias-em-santana\/"},{"label":"Bilhete \u00danico ganha recarga m\u00f3vel no Metr\u00f4 Santana","link":"https:\/\/www.encontrasantana.com.br\/sobre\/bilhete-unico-ganha-recarga-movel-no-metro-santana\/"}],"_links":{"self":[{"href":"https:\/\/www.encontrasantana.com.br\/sobre\/wp-json\/wp\/v2\/posts\/39033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontrasantana.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrasantana.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrasantana.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrasantana.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=39033"}],"version-history":[{"count":0,"href":"https:\/\/www.encontrasantana.com.br\/sobre\/wp-json\/wp\/v2\/posts\/39033\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.encontrasantana.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=39033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrasantana.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=39033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrasantana.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=39033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}